{"id":5586,"date":"2022-07-07T15:49:47","date_gmt":"2022-07-07T15:49:47","guid":{"rendered":"https:\/\/alst.org\/?p=5586"},"modified":"2024-03-12T06:31:27","modified_gmt":"2024-03-12T06:31:27","slug":"la-famiglia-danner","status":"publish","type":"post","link":"https:\/\/alst.org\/it\/istruzione\/biografie\/la-famiglia-danner\/","title":{"rendered":"La famiglia Danner"},"content":{"rendered":"\n<figure class=\"wp-block-image alignright size-full\"><img decoding=\"async\" width=\"107\" height=\"180\" src=\"https:\/\/alst.org\/wp-content\/uploads\/2022\/07\/Danner-Jacques.jpeg\" alt=\"\" class=\"wp-image-5332\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La famiglia Danner viveva al 3, rue des Seigneurs a Basse Yutz, in Mosella (Francia). Il padre, Jacques Danner, soprannominato&nbsp; \u201cJacob\u201d, nato il 22 marzo 1898 a Rohrbach, lavorava come operaio agli altiforni. Aveva sposato Augustine Rosine Hantz, nata il 25 febbraio 1899.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il 19 gennaio 1922, nacque la prima figlia, H\u00e9l\u00e8ne e, circa dodici anni dopo, il 9 dicembre 1933, l\u2019ultimogenita, Ruth. Nel frattempo, i Danner si erano uniti al movimento religioso dei Testimoni di Geova \u2013 pi\u00f9 conosciuti all\u2019epoca sotto il nome di Studenti biblici (o Bibelforscher, nei paesi di lingua tedesca). Perci\u00f2, Jacques scelse di fare il falegname per non lavorare di sera. Questo gli avrebbe permesso di partecipare alle adunanze bibliche. Lui e sua moglie dedicavano comunque la maggior parte del loro tempo all\u2019opera che consiste a diffondere la conoscenza della Bibbia ai loro concittadini. Da quell\u2019attivit\u00e0, in una regione fortemente cattolica, ne consegu\u00ec la loro messa al bando dalla societ\u00e0 locale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 1941, l\u2019invasione dell\u2019Alsazia-Lorena dalle truppe tedesche fu una prova ancora pi\u00f9 terribile per i Danner. All\u2019epoca, H\u00e9l\u00e8ne era una collaboratrice familiare, e Ruth una scolara. Hitler decise che la regione doveva integrarsi nella Volksgemeinschaft e impose il saluto nazista obbligatorio nella regione annessa. La piccola Ruth, che si era gi\u00e0 fatta notare per essersi opposta alla propria partecipazione alle preghiere pubbliche cattoliche a scuola, si rifiut\u00f2 categoricamente di dire \u201cHeil Hitler\u201d, nonostante le angherie e le botte. Quell\u2019atteggiamento attir\u00f2 l\u2019attenzione della Gestapo che sottopose i genitori a degli interrogatori regolari e prolungati. Perci\u00f2, la ragazzina si ritrov\u00f2 spesso seduta sulla soglia di casa ad aspettare il loro ritorno.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><img decoding=\"async\" width=\"113\" height=\"180\" src=\"https:\/\/alst.org\/wp-content\/uploads\/2022\/07\/Danner-Augustine.jpeg\" alt=\"\" class=\"wp-image-5338\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il 28 gennaio 1943, l\u2019intera famiglia fu caricata su un pullman diretto alla stazione di Metz dove aspettava il treno che li avrebbe deportati in Pologna. Gli agenti della Gestapo permisero ai vicini dei Danner&nbsp; di saccheggiare i loro beni \u201cperch\u00e9\u201d, precisarono, \u201cnon ne avranno mai pi\u00f9 bisogno\u201d. Jacques, Augustine, H\u00e9l\u00e8ne e Ruth arrivarono in Alta-Slesia dopo un viaggio di tre giorni e furono successivamente rinchiusi negli stessi campi di lavoro : Kochlowitz, Schwientochlowitz, Wolfsdorf e Frankenstein. Quando Jacques fu mandato da solo nel campo di Gutendorf, sua moglie e le sue due figlie, senza notizie, temerono di non rivederlo mai pi\u00f9, ma fortunatamente la separazione fu di breve durata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le condizioni di vita in quei campi di lavoro erano estremamente difficile : promiscuit\u00e0, baracche infestate di parassiti, scarsa emissione d\u2019acqua dal rubinetto\u2026 Il lavoro era estenuante, gli uomini faticavano nelle miniere di rame, le donne nei cantieri di costruzione. Persino i bambini dovevano partecipare ai lavori forzati gi\u00e0 dall\u2019et\u00e0 di tre anni. Le cure mediche erano rudimentali : quando la piccola Ruth soffr\u00ec&nbsp; del male bianco (tipo di patereccio), il \u201crimedio\u201d consist\u00e9 nello strapparle le unghie colpite senza nessun\u2019anestesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il 19 febbraio 1945, per via dell\u2019avanzata dell\u2019Armata rossa, tutti i detenuti furono evacuati a piedi verso l\u2019Ovest. La famiglia Danner, stremata e coperta di parassiti, fu finalmente liberata il 5 maggio 1945 dopo una lunga marcia caotica di 245 km che dur\u00f2 diverse settimane. Al loro ritorno a Basse Yutz, il loro ex-proprietario fece in modo di farli ritornare nella loro casa, danneggiata da una granata. Qualche vicino restitu\u00ec loro persino certi beni di cui si erano appropriati.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full\"><img decoding=\"async\" width=\"115\" height=\"172\" src=\"https:\/\/alst.org\/wp-content\/uploads\/2022\/07\/Danner-Ruth.jpeg\" alt=\"\" class=\"wp-image-5343\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Jacques trov\u00f2 prima un impiego come pontoniere, poi&nbsp;come fabbro per provvedere alla sua famiglia. Tuttavia, sia i genitori Danner che le loro figlie, H\u00e9l\u00e8ne e Ruth, colmi di gratitudine per essere sopravvissuti, dedicarono la maggior parte del loro tempo all\u2019opera cristiana d\u2019evangelizzazione in Lorena. In seguito, Ruth si un\u00ec pure al CETJAD (Circolo europeo dei Testimoni di Geova ex-deportati), di cui divent\u00f2 la presidente. Jacques Danner mor\u00ec nel 1978 all\u2019et\u00e0 di 80 anni, e Augustine, sua moglie, dieci anni pi\u00f9 tardi a 89 anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La famiglia Danner viveva al 3, rue des Seigneurs a Basse Yutz, in Mosella (Francia). Il padre, Jacques Danner, soprannominato&nbsp; \u201cJacob\u201d, nato il 22 marzo 1898 a Rohrbach, lavorava come operaio agli altiforni. Aveva sposato Augustine Rosine Hantz, nata il 25 febbraio 1899. Il 19 gennaio 1922, nacque la prima figlia, H\u00e9l\u00e8ne e, circa dodici [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[159,173],"tags":[],"class_list":["post-5586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biografie","category-biografie-it"],"_links":{"self":[{"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/posts\/5586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/comments?post=5586"}],"version-history":[{"count":3,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/posts\/5586\/revisions"}],"predecessor-version":[{"id":9689,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/posts\/5586\/revisions\/9689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/media\/5332"}],"wp:attachment":[{"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/media?parent=5586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/categories?post=5586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alst.org\/it\/wp-json\/wp\/v2\/tags?post=5586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}